{"id":20091,"date":"2021-08-28T20:39:34","date_gmt":"2021-08-28T20:39:34","guid":{"rendered":"https:\/\/blog.salarusinyol.net\/2021\/08\/28\/4-anotacions-de-mangot\/"},"modified":"2021-08-28T20:39:34","modified_gmt":"2021-08-28T20:39:34","slug":"4-anotacions-de-mangot","status":"publish","type":"post","link":"https:\/\/blog.salarusinyol.net\/es\/2021\/08\/28\/4-anotacions-de-mangot\/","title":{"rendered":"4 anotacions de\u2026 Mangot"},"content":{"rendered":"<p><strong>Respuestas r\u00e1pidas del artista, sin \u00abbuscar 3 patas al gato\u00bb<a rel=\"attachment wp-att-2738\" href=\"http:\/\/blogcat.salarusinyol.net\/?attachment_id=2738\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-2738\" title=\"mangot-51\" src=\"http:\/\/bloc.salarusinyol.net\/wp-content\/uploads\/2010\/06\/mangot-51-150x150.jpg\" alt=\"mangot-51\" width=\"123\" height=\"123\" \/><\/a><\/strong><\/p>\n<ul>\n<li> <strong>T\u00fa? <\/strong>(nombre completo; poblaci\u00f3n y a\u00f1o nacimiento; y lo que quieras): Montserrat Padr\u00f3s Mangot. Como artista: Mangot. Barcelona, 1937. Casada con Ram\u00f3n; con hijos y nietos: uno de ellos, de 17 a\u00f1os, Rom\u00e0, pinta y me acompa\u00f1a a pintar en la calle. Otra de 8 a\u00f1os, Ruth, tambi\u00e9n pinta; su hermano gemelo, Gabriel, es m\u00fasico.<!--more--><\/li>\n<li> <strong>Una virtud tuya a destacar?<\/strong>: La puntualidad.<\/li>\n<li> <strong>Un punto flaco tuyo a reconocer?<\/strong>: Me precipito con las cosas: hago lo que siento. Es decir, soy impulsiva.<\/li>\n<li> <strong>Tu plato preferido? <\/strong>(para quien desee invitarte): Sopa <em>bullebesa<\/em> (es una sopa muy especial, de pescado escogido).<\/li>\n<li> <strong>Un recuerdo de tu vida?<\/strong>: Los cerezos floridos de casa de mi padre.<\/li>\n<li> <strong>Un lugar de este mundo?<\/strong>: El Cairo, Egipto.<\/li>\n<li> <strong>Un libro?<\/strong>: <em>\u00abEl ni\u00f1o con el pijama de rayas\u00bb<\/em>, de John Boyne.<\/li>\n<li> <strong>Un escritor?<\/strong>: Shakespeare. Aunque, de hecho, m\u00e1s bien leo libros sobre arte y sobre psicolog\u00eda.<\/li>\n<li> <strong>Del \u00abs\u00e9ptimo arte\u00bb: una pel\u00edcula?<\/strong>: <em>\u00abLo que el viento se llev\u00f3\u00bb<\/em>.<\/li>\n<li> <strong>Una afici\u00f3n?<\/strong>: Andar.<a rel=\"attachment wp-att-2740\" href=\"http:\/\/blogcat.salarusinyol.net\/?attachment_id=2740\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-2740\" title=\"mangot-521\" src=\"http:\/\/bloc.salarusinyol.net\/wp-content\/uploads\/2010\/06\/mangot-521-150x150.jpg\" alt=\"mangot-521\" width=\"150\" height=\"150\" \/><\/a><\/li>\n<li> <strong>Un sue\u00f1o?<\/strong>: Volar, sentirme vol\u00e1til, poderme trasladar como un p\u00e1jaro&#8230;<\/li>\n<li> <strong>Qu\u00e9 es el arte?<\/strong>: Una atracci\u00f3n sublime y sobrenatural.<\/li>\n<li> <strong>Para Plat\u00f3n<\/strong>, <em>la <strong>belleza<\/strong> es la llamada de <strong>otro mundo<\/strong> para rescatarnos de la caverna donde vivimos<\/em>: (qu\u00e9 te parece?): \u00a1Me parece perfecto! Eso encaja con la ilusi\u00f3n y el sue\u00f1o que antes he descrito.<\/li>\n<li> <strong>Te has encontrado con la <span style=\"text-decoration: underline;\">B<\/span>elleza (as\u00ed, en <span style=\"text-decoration: underline;\">M<\/span>ay\u00fascula)?<\/strong>: S\u00ed, pero la belleza dura poco: por unos instantes. Contemplar la salida del sol, el mar, por la ma\u00f1ana o\u00edr los p\u00e1jaros&#8230; son momentos de belleza sublime.<\/li>\n<li> <strong>Tu maestro?<\/strong>: La naturaleza.<\/li>\n<li> <strong>Te identificas con alguna escuela de pintura?<\/strong>: Bastante con los expresionistas, con los que pintan abstracto sint\u00e9tico (simplificar pinceladas con una sola).<\/li>\n<li> <strong>Un pintor que admiras?<\/strong>: De la escuela austr\u00edaca, Egon Schiele, Karel Appel, Van Ghogh, Monet&#8230;<\/li>\n<li> <strong>Tu primer recuerdo del mundo del arte?<\/strong>: Una galer\u00eda en el Paseo de Gracia: la Galer\u00eda Sira<a rel=\"attachment wp-att-2741\" href=\"http:\/\/blogcat.salarusinyol.net\/?attachment_id=2741\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-2741\" title=\"mangot-53\" src=\"http:\/\/bloc.salarusinyol.net\/wp-content\/uploads\/2010\/06\/mangot-53-150x150.jpg\" alt=\"mangot-53\" width=\"150\" height=\"150\" \/><\/a><\/li>\n<li> <strong>Tu primera alegr\u00eda en el arte?<\/strong>: Una vez que pintaba en la calle y hab\u00eda un se\u00f1or detr\u00e1s de m\u00ed, y me dijo: -Ahora s\u00f3lo te falta firmar y poner Mangot. -Qu\u00e9 me conoces? S\u00ed, tengo 3 cuadros tuyos&#8230; Ya me conoc\u00eda el estilo.<\/li>\n<li> <strong>Tu primera exposici\u00f3n?<\/strong>: Fant\u00e1stica: en Vidreras; llov\u00eda mucho; en media hora lo vend\u00ed todo. A\u00f1o &#8217;76.<\/li>\n<li> <strong>Tu estilo?<\/strong>: \u00abFigurativo\u00bb (aunque no realista), \u00abexpresionista\u00bb (porque comunico las impresiones y las sensaciones m\u00e1s fuertes), \u00ababstracto\u00bb (porque separo por operaci\u00f3n intelectual las cualidades del objeto en esencia pura) y \u00absint\u00e9tico\u00bb (porque de varias pinceladas hago una sola). Aun no estoy definida: me tienen que catalogar con el tiempo: es el estilo Mangot.<\/li>\n<li> <strong>Tu color?<\/strong>: Los lilas.<\/li>\n<li> <strong>Tu tema?<\/strong>: Barcelona, me gusta interiores, marinas&#8230; lo hago todo. Lo que m\u00e1s me gusta es la figura, el retrato, porque capto la psicolog\u00eda de la persona.<\/li>\n<li> <strong>Nos dices algo m\u00e1s?<\/strong> (lo que quieras de lo que quieras): Lo que m\u00e1s me gusta es pintar personas. Pero antes debo conocerlas. Luego las represento con la emoci\u00f3n y su car\u00e1cter. Procuro captar el movimiento: los \u00e1rboles&#8230;, el mar, la gente cuando habla que se note&#8230;<\/li>\n<li> <strong>Alguna otra pregunta? <\/strong>(que deseas que te hagamos): No.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Respuestas r\u00e1pidas del artista, sin \u00abbuscar 3 patas al gato\u00bb T\u00fa? (nombre completo; poblaci\u00f3n y a\u00f1o nacimiento; y lo que quieras): Montserrat Padr\u00f3s Mangot. Como artista: Mangot. Barcelona, 1937. Casada con Ram\u00f3n; con hijos y nietos: uno de ellos, de 17 a\u00f1os, Rom\u00e0, pinta y me acompa\u00f1a a pintar en la calle. Otra de 8 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-20091","post","type-post","status-publish","format-standard","hentry","category-4-apuntes-de"],"_links":{"self":[{"href":"https:\/\/blog.salarusinyol.net\/es\/wp-json\/wp\/v2\/posts\/20091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.salarusinyol.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.salarusinyol.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/es\/wp-json\/wp\/v2\/comments?post=20091"}],"version-history":[{"count":0,"href":"https:\/\/blog.salarusinyol.net\/es\/wp-json\/wp\/v2\/posts\/20091\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.salarusinyol.net\/es\/wp-json\/wp\/v2\/media?parent=20091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/es\/wp-json\/wp\/v2\/categories?post=20091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/es\/wp-json\/wp\/v2\/tags?post=20091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}