{"id":19957,"date":"2021-08-28T20:39:19","date_gmt":"2021-08-28T20:39:19","guid":{"rendered":"https:\/\/blog.salarusinyol.net\/2021\/08\/28\/la-propera-andreu-fresquet-14-vi-10-vii-2013\/"},"modified":"2021-08-28T20:39:19","modified_gmt":"2021-08-28T20:39:19","slug":"la-propera-andreu-fresquet-14-vi-10-vii-2013","status":"publish","type":"post","link":"https:\/\/blog.salarusinyol.net\/es\/2021\/08\/28\/la-propera-andreu-fresquet-14-vi-10-vii-2013\/","title":{"rendered":"\u00abLa propera\u00bb: Andreu Fresquet (14.VI-10.VII.2013)"},"content":{"rendered":"<p><strong><em> <\/em><\/strong><\/p>\n<p>Andreu Fresquet, artista d\u2019\u00e0mplia traject\u00f2ria, ens presenta una extraordin\u00e0ria mostra dels seus darrers treballs\u00a0 per cloure la temporada d\u2019exposicions de la Sala Rusi\u00f1ol.<br \/>\n<a rel=\"attachment wp-att-5079\" href=\"http:\/\/blogcat.salarusinyol.net\/2013\/06\/11\/la-propera-andreu-fresquet-14-vi-10-vii-2013\/aq-13164\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-5079\" title=\"AQ-13164\" src=\"http:\/\/blogcat.salarusinyol.net\/wp-content\/uploads\/2013\/06\/AQ-13164-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><br \/>\n<a href=\"http:\/\/www.salarusinyol.net\/cat\/exposicions\/pro_cat.html\">\u201cRitmes, moviment i atmosfera\u201d<\/a> \u00e9s la proposta que ens ofereix i ens trobem amb l\u2019agradable sorpresa de qu\u00e8 mant\u00e9, amb m\u00e9s intensitat en els continguts, aquelles formes expressives que sempre ens han atret -bodegons i composicions de fruites, teteres i tasses de blanca porcellana, moviments de dansa- i que, en resum, s\u00f3n un desig de llibertat.<\/p>\n<p>El periodista i cr\u00edtic d\u2019art Josep M. Cadena ser\u00e0 l\u2019encarregat del comentari cr\u00edtic que tindr\u00e0 lloc\u00a0 DIVENDRES, dia 14, a les 19.30 h.<\/p>\n<p>Us hi esperem!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Andreu Fresquet, artista d\u2019\u00e0mplia traject\u00f2ria, ens presenta una extraordin\u00e0ria mostra dels seus darrers treballs\u00a0 per cloure la temporada d\u2019exposicions de la Sala Rusi\u00f1ol. \u201cRitmes, moviment i atmosfera\u201d \u00e9s la proposta que ens ofereix i ens trobem amb l\u2019agradable sorpresa de qu\u00e8 mant\u00e9, amb m\u00e9s intensitat en els continguts, aquelles formes expressives que sempre ens han [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-19957","post","type-post","status-publish","format-standard","hentry","category-la-propera-es"],"_links":{"self":[{"href":"https:\/\/blog.salarusinyol.net\/es\/wp-json\/wp\/v2\/posts\/19957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.salarusinyol.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.salarusinyol.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/es\/wp-json\/wp\/v2\/comments?post=19957"}],"version-history":[{"count":0,"href":"https:\/\/blog.salarusinyol.net\/es\/wp-json\/wp\/v2\/posts\/19957\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.salarusinyol.net\/es\/wp-json\/wp\/v2\/media?parent=19957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/es\/wp-json\/wp\/v2\/categories?post=19957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/es\/wp-json\/wp\/v2\/tags?post=19957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}