{"id":20192,"date":"2021-08-28T20:39:44","date_gmt":"2021-08-28T20:39:44","guid":{"rendered":"https:\/\/blog.salarusinyol.net\/2021\/08\/28\/la-propera-curell-7-3-2-4-2019\/"},"modified":"2021-08-28T20:39:44","modified_gmt":"2021-08-28T20:39:44","slug":"la-propera-curell-7-3-2-4-2019","status":"publish","type":"post","link":"https:\/\/blog.salarusinyol.net\/en\/2021\/08\/28\/la-propera-curell-7-3-2-4-2019\/","title":{"rendered":"La propera: Curell (7.3-2.4.2019)"},"content":{"rendered":"<p>Mar i cel, lluna plena, blaus actius i barques vistes des de l\u2019aire, platges daurades i ciutats que s\u2019expandeixen, s\u00f3n els elements que la pintora ens ofereix amb intensitat de missatge dins de l\u2019aparent senzillesa d\u2019expressi\u00f3.<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-15242 alignright\" src=\"https:\/\/salarusinyol.net\/wp-content\/uploads\/2019\/02\/CUR19040-300x222.jpg\" alt=\"\" width=\"300\" height=\"222\" \/><\/p>\n<p>Els llen\u00e7os de Dolors Curell capturen les belleses naturals \u2013els cels en els que la llum s\u2019obre pas a trav\u00e9s dels n\u00favols, les diferents tonalitats de les aig\u00fces que deixen veure el verd de la vegetaci\u00f3 aqu\u00e0tica i el daurat de la sorra, les games marronoses dels camps de cultiu&#8230;\u2013 i a la vegada reflexionen sobre la magnitud de l\u2019univers en el que tenen lloc les nostres fugaces vides.<\/p>\n<p>Les escenes captades per l\u2019artista ens conviden a gaudir dels plaers del m\u00f3n.\u00a0Per\u00f2 tamb\u00e9 ens recorden que ens movem sobre uns misteris tan insondables com les foses marines i que sempre es bo aixecar la vista cap al cel de la transcend\u00e8ncia. I aquestes lli\u00e7ons ens arriben mitjan\u00e7ant uns quadres dominats per l\u2019excel\u00b7l\u00e8ncia est\u00e8tica.<\/p>\n<p>La inauguraci\u00f3, <b>DIJOUS 7 DE MAR\u00c7 A LES 19.30 h,\u00a0<\/b>amb la pres\u00e8ncia de l&#8217;artista, s&#8217;acompanyar\u00e0 del\u00a0comentari cr\u00edtic\u00a0d&#8217;en Josep M. Cadena.<\/p>\n<p><strong>ESTEU CONVIDATS<br \/>\nUS HI ESPEREM!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mar i cel, lluna plena, blaus actius i barques vistes des de l\u2019aire, platges daurades i ciutats que s\u2019expandeixen, s\u00f3n els elements que la pintora ens ofereix amb intensitat de missatge dins de l\u2019aparent senzillesa d\u2019expressi\u00f3. Els llen\u00e7os de Dolors Curell capturen les belleses naturals \u2013els cels en els que la llum s\u2019obre pas a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-20192","post","type-post","status-publish","format-standard","hentry","category-la-propera-en"],"_links":{"self":[{"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/posts\/20192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/comments?post=20192"}],"version-history":[{"count":0,"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/posts\/20192\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/media?parent=20192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/categories?post=20192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/tags?post=20192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}