{"id":20167,"date":"2021-08-28T20:39:42","date_gmt":"2021-08-28T20:39:42","guid":{"rendered":"https:\/\/blog.salarusinyol.net\/2021\/08\/28\/vernissatge-de-miquel-peidro-7-setembre-2012\/"},"modified":"2021-08-28T20:39:42","modified_gmt":"2021-08-28T20:39:42","slug":"vernissatge-de-miquel-peidro-7-setembre-2012","status":"publish","type":"post","link":"https:\/\/blog.salarusinyol.net\/en\/2021\/08\/28\/vernissatge-de-miquel-peidro-7-setembre-2012\/","title":{"rendered":"Vernissatge de Miquel Peidro (7 setembre 2012)"},"content":{"rendered":"<p><a rel=\"attachment wp-att-4421\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/04\/18\/vernissatge-den-tenorio-13-abril-2012\/01-tenorio-4\/\"><\/a><a rel=\"attachment wp-att-4432\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/05\/14\/vernissatge-den-lluis-roura-4-maig-2012\/01-roura\/\"><\/a><a rel=\"attachment wp-att-4506\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/06\/15\/vernissatge-daguilar-more\/01-aguilar-more\/\"><\/a><a rel=\"attachment wp-att-4511\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/06\/15\/vernissatge-daguilar-more\/01-aguilar-more-2\/\"><\/a><a rel=\"attachment wp-att-4552\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/09\/18\/vernissatge-de-miquel-peidro-7-setembre-2012\/01-peidro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-4552\" title=\"01 Peidro\" src=\"http:\/\/blogcat.salarusinyol.net\/wp-content\/uploads\/2012\/09\/01-Peidro-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p><a rel=\"attachment wp-att-4226\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/01\/22\/vernissatge-den-malvehy-13-gener-2012\/01-malvehy\/\"><\/a><a rel=\"attachment wp-att-4274\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/02\/12\/vernissatge-den-vives-fierro-3-febrer-2012\/01-vives-fierro-2\/\"><\/a><a rel=\"attachment wp-att-4309\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/03\/05\/vernissatge-de-xavier-sanagustin-24-febrer-2012\/sanagustin-01\/\"><\/a><a rel=\"attachment wp-att-4358\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/03\/23\/vernissatge-de-roman-frances-16-marc-2012\/01-roman-frances-2\/\"><\/a><a rel=\"attachment wp-att-4397\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/04\/18\/vernissatge-den-tenorio-13-abril-2012\/01-tenorio\/\"><\/a><a rel=\"attachment wp-att-4415\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/04\/18\/vernissatge-den-tenorio-13-abril-2012\/01-tenorio-2\/\"><\/a><\/p>\n<div style=\"height: 190px;\">\n<p><strong> <\/strong><strong> <\/strong><em> <\/em>Seguint el ritme dels nens a les escoles, a la <strong>Sala Rusi\u00f1ol<\/strong> tamb\u00e9 comencem un nou &#8220;curs&#8221;. Aquesta vegada, tenim la sort de fer-ho amb l&#8217;extraordin\u00e0ria mostra d&#8217;un pintor in\u00e8dit a casa nostra: en <strong>Miquel Peidro <\/strong>(<strong><em><span style=\"text-decoration: underline;\"><a href=\"http:\/\/www.salarusinyol.net\/cat\/exposicions\/2012-09_cat.html\">&#8220;La for\u00e7a del color&#8221;<\/a><\/span><\/em><\/strong>). Vingut d&#8217;Alcoy, per\u00f2 arribat des del Jap\u00f3, on est\u00e0 triomfant despr\u00e9s d&#8217;unes quantes exposicions. Interessant la seva experi\u00e8ncia al pa\u00eds nip\u00f3!<!--more--><\/p>\n<\/div>\n<div style=\"height: 200px;\">\n<p><a rel=\"attachment wp-att-4507\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/06\/15\/vernissatge-daguilar-more\/02-aguilar-more\/\"><\/a><a rel=\"attachment wp-att-4553\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/09\/18\/vernissatge-de-miquel-peidro-7-setembre-2012\/02-peidro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-4553\" title=\"02 Peidro\" src=\"http:\/\/blogcat.salarusinyol.net\/wp-content\/uploads\/2012\/09\/02-Peidro-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><strong> <\/strong><strong> <\/strong>Es el moment de les <strong><em><span style=\"text-decoration: underline;\"><a href=\"http:\/\/blogcat.salarusinyol.net\/2012\/09\/18\/4-anotacions-den-peidro\/#more-4541\">&#8220;4 anotacions d&#8217;en&#8230; Peidro&#8221;<\/a><\/span><\/em><\/strong>. \u00c9s un moment d&#8217;intimitat, en el qual l&#8217;artista ens descobreix coses que no surten habitualment. Per exemple, li v\u00e0rem preguntar: <strong>Un r\u00e8cord en la teva vida? (pregunta afegida per suggeriment del pintor Rom\u00e1n Franc\u00e9s)<\/strong>: \u00abAls 56 anys vaig ser l&#8217;espanyol de m\u00e9s edat que vaig travessar l&#8217;Estret de Gibraltar nedant. Era l&#8217;any 2006. A voltes em diuen que s\u00f3c un poc rar per a ser artista: sembla rar que jo, artista, sigui a m\u00e9s esportista\u00bb.<\/p>\n<\/div>\n<div style=\"height: 190px; text-align: right;\"><a rel=\"attachment wp-att-4508\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/06\/15\/vernissatge-daguilar-more\/03-aguilar-more\/\"><\/a><a rel=\"attachment wp-att-4554\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/09\/18\/vernissatge-de-miquel-peidro-7-setembre-2012\/03-peidro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-4554\" title=\"03 Peidro\" src=\"http:\/\/blogcat.salarusinyol.net\/wp-content\/uploads\/2012\/09\/03-Peidro-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a> <strong><\/strong><strong><\/strong><strong>Josep M\u00aa Cadena<\/strong>. Es refer\u00ed al comen\u00e7ament de la temporada: \u00abEnlla\u00e7a amb el passat, obre cap al futur, perqu\u00e8 aquesta sala ja t\u00e9 la suficient traject\u00f2ria, la suficient capacitat per anar presentant de manera peri\u00f2dica tot un conjunt de pintura diferent, per\u00f2 en la que sempre es busca la qualitat\u00bb.<\/div>\n<div style=\"height: 190px; text-align: left;\">\n<p><strong><strong><a rel=\"attachment wp-att-4509\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/06\/15\/vernissatge-daguilar-more\/04-aguilar-more\/\"><\/a><a rel=\"attachment wp-att-4555\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/09\/18\/vernissatge-de-miquel-peidro-7-setembre-2012\/04-peidro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-4555\" title=\"04 Peidro\" src=\"http:\/\/blogcat.salarusinyol.net\/wp-content\/uploads\/2012\/09\/04-Peidro-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/strong><\/strong><strong> <\/strong><strong><\/strong><strong><\/strong>\u00abPer al cas d&#8217;en Miquel Peidro, voldria dir una frase que podria semblar una mica agosarada: moltes vegades l&#8217;art es vol assemblar a la naturalesa, per\u00f2, davant de les seves obres, \u00e9s la naturalesa la que voldria assemblar-se a la seva pintura. \u00c9s a dir, que la naturalesa voldria conservar durant el m\u00e0xim de temps possible aquestes tonalitats, aquest joc de colors&#8230;, on els arbres, els rius, les pedres, la terra es troben amb una determinada conjunci\u00f3 de satisfacci\u00f3\u00bb.<\/p>\n<\/div>\n<div style=\"height: 210px; text-align: right;\">\n<p><a rel=\"attachment wp-att-4512\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/06\/15\/vernissatge-daguilar-more\/05-aguilar-more-2\/\"><\/a><a rel=\"attachment wp-att-4556\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/09\/18\/vernissatge-de-miquel-peidro-7-setembre-2012\/05-peidro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-4556\" title=\"05 Peidro\" src=\"http:\/\/blogcat.salarusinyol.net\/wp-content\/uploads\/2012\/09\/05-Peidro-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><strong> <\/strong><strong><\/strong>\u00abMoltes gr\u00e0cies a la Sala per la delicadesa i la forma com ha muntat l&#8217;exposici\u00f3. Jo sempre dic que, des del moment que el quadre eix del cavallet, el pintor t\u00e9 que callar, ha de parlar l&#8217;obra&#8230; M&#8217;agradaria dir-vos lo que intenta el meu treball: l&#8217;art \u00e9s una manera de transmitir lo que l&#8217;artista vol dir. En el meu cas, la manera de transmetre va un poc al m\u00f3n de les sensacions, dels sentiments. Vull que sentiu el que jo vaig sentir quan estava pintant. Intento transmitir dues passions: el meu amor per a la natura i el meu amor per a la pintura\u00bb.<\/p>\n<\/div>\n<p style=\"text-align: center;\"><strong>M\u00c9S FOTOS  DEL VERSISSATGE<\/strong><\/p>\n<div style=\"height: 160px; display: block;\"><a rel=\"attachment wp-att-4438\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/05\/14\/vernissatge-den-lluis-roura-4-maig-2012\/06-roura\/\"><\/a><a rel=\"attachment wp-att-4513\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/06\/15\/vernissatge-daguilar-more\/06-aguilar-more\/\"><\/a><a rel=\"attachment wp-att-4557\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/09\/18\/vernissatge-de-miquel-peidro-7-setembre-2012\/06-peidro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-4557\" title=\"06 Peidro\" src=\"http:\/\/blogcat.salarusinyol.net\/wp-content\/uploads\/2012\/09\/06-Peidro-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/div>\n<div style=\"height: 160px; display: block;\"><a rel=\"attachment wp-att-4439\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/05\/14\/vernissatge-den-lluis-roura-4-maig-2012\/07-roura\/\"><\/a><a rel=\"attachment wp-att-4514\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/06\/15\/vernissatge-daguilar-more\/07-aguilar-more\/\"><\/a><a rel=\"attachment wp-att-4558\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/09\/18\/vernissatge-de-miquel-peidro-7-setembre-2012\/07-peidro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-4558\" title=\"07 Peidro\" src=\"http:\/\/blogcat.salarusinyol.net\/wp-content\/uploads\/2012\/09\/07-Peidro-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/div>\n<div style=\"height: 160px; display: block;\"><a rel=\"attachment wp-att-4440\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/05\/14\/vernissatge-den-lluis-roura-4-maig-2012\/08-roura\/\"><\/a><a rel=\"attachment wp-att-4515\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/06\/15\/vernissatge-daguilar-more\/08-aguilar-more\/\"><\/a><a rel=\"attachment wp-att-4559\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/09\/18\/vernissatge-de-miquel-peidro-7-setembre-2012\/08-peidro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-4559\" title=\"08 Peidro\" src=\"http:\/\/blogcat.salarusinyol.net\/wp-content\/uploads\/2012\/09\/08-Peidro-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/div>\n<div style=\"height: 160px; display: block;\">\n<p><a rel=\"attachment wp-att-4441\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/05\/14\/vernissatge-den-lluis-roura-4-maig-2012\/09-roura\/\"><\/a><a rel=\"attachment wp-att-4516\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/06\/15\/vernissatge-daguilar-more\/09-aguilar-more\/\"><\/a><a rel=\"attachment wp-att-4560\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/09\/18\/vernissatge-de-miquel-peidro-7-setembre-2012\/09-peidro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-4560\" title=\"09 Peidro\" src=\"http:\/\/blogcat.salarusinyol.net\/wp-content\/uploads\/2012\/09\/09-Peidro-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<\/div>\n<div style=\"height: 160px; display: block;\">\n<p><a rel=\"attachment wp-att-4442\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/05\/14\/vernissatge-den-lluis-roura-4-maig-2012\/10-roura\/\"><\/a><a rel=\"attachment wp-att-4517\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/06\/15\/vernissatge-daguilar-more\/10-aguilar-more\/\"><\/a><a rel=\"attachment wp-att-4561\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/09\/18\/vernissatge-de-miquel-peidro-7-setembre-2012\/10-peidro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-4561\" title=\"10 Peidro\" src=\"http:\/\/blogcat.salarusinyol.net\/wp-content\/uploads\/2012\/09\/10-Peidro-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<\/div>\n<div style=\"height: 160px; display: block;\">\n<p><a rel=\"attachment wp-att-4443\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/05\/14\/vernissatge-den-lluis-roura-4-maig-2012\/11-roura\/\"><\/a><a rel=\"attachment wp-att-4518\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/06\/15\/vernissatge-daguilar-more\/11-aguilar-more\/\"><\/a><a rel=\"attachment wp-att-4562\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/09\/18\/vernissatge-de-miquel-peidro-7-setembre-2012\/11-peidro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-4562\" title=\"11 Peidro\" src=\"http:\/\/blogcat.salarusinyol.net\/wp-content\/uploads\/2012\/09\/11-Peidro-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<\/div>\n<div style=\"height: 160px; display: block;\">\n<p><a rel=\"attachment wp-att-4444\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/05\/14\/vernissatge-den-lluis-roura-4-maig-2012\/12-roura\/\"><\/a><a rel=\"attachment wp-att-4519\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/06\/15\/vernissatge-daguilar-more\/12-aguilar-more\/\"><\/a><a rel=\"attachment wp-att-4563\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/09\/18\/vernissatge-de-miquel-peidro-7-setembre-2012\/12-peidro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-4563\" title=\"12 Peidro\" src=\"http:\/\/blogcat.salarusinyol.net\/wp-content\/uploads\/2012\/09\/12-Peidro-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<\/div>\n<div style=\"height: 160px; display: block;\">\n<p><a rel=\"attachment wp-att-4446\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/05\/14\/vernissatge-den-lluis-roura-4-maig-2012\/14-roura\/\"><\/a><a rel=\"attachment wp-att-4520\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/06\/15\/vernissatge-daguilar-more\/13-aguilar-more\/\"><\/a><a rel=\"attachment wp-att-4564\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/09\/18\/vernissatge-de-miquel-peidro-7-setembre-2012\/13-peidro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-4564\" title=\"13 Peidro\" src=\"http:\/\/blogcat.salarusinyol.net\/wp-content\/uploads\/2012\/09\/13-Peidro-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<\/div>\n<div style=\"height: 160px; display: block;\">\n<p><a rel=\"attachment wp-att-4447\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/05\/14\/vernissatge-den-lluis-roura-4-maig-2012\/15-roura\/\"><\/a><a rel=\"attachment wp-att-4521\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/06\/15\/vernissatge-daguilar-more\/14-aguilar-more\/\"><\/a><a rel=\"attachment wp-att-4565\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/09\/18\/vernissatge-de-miquel-peidro-7-setembre-2012\/14-peidro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-4565\" title=\"14 Peidro\" src=\"http:\/\/blogcat.salarusinyol.net\/wp-content\/uploads\/2012\/09\/14-Peidro-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<\/div>\n<div style=\"height: 160px; display: block;\">\n<p><a rel=\"attachment wp-att-4447\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/05\/14\/vernissatge-den-lluis-roura-4-maig-2012\/15-roura\/\"><\/a><a rel=\"attachment wp-att-4521\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/06\/15\/vernissatge-daguilar-more\/14-aguilar-more\/\"><\/a><a rel=\"attachment wp-att-4531\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/06\/15\/vernissatge-daguilar-more\/15-aguilar-more\/\"><\/a><a rel=\"attachment wp-att-4566\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/09\/18\/vernissatge-de-miquel-peidro-7-setembre-2012\/15-peidro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-4566\" title=\"15 Peidro\" src=\"http:\/\/blogcat.salarusinyol.net\/wp-content\/uploads\/2012\/09\/15-Peidro-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Seguint el ritme dels nens a les escoles, a la Sala Rusi\u00f1ol tamb\u00e9 comencem un nou &#8220;curs&#8221;. Aquesta vegada, tenim la sort de fer-ho amb l&#8217;extraordin\u00e0ria mostra d&#8217;un pintor in\u00e8dit a casa nostra: en Miquel Peidro (&#8220;La for\u00e7a del color&#8221;). Vingut d&#8217;Alcoy, per\u00f2 arribat des del Jap\u00f3, on est\u00e0 triomfant despr\u00e9s d&#8217;unes quantes exposicions. Interessant [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-20167","post","type-post","status-publish","format-standard","hentry","category-vernissatges-a-la-sala-rusinol"],"_links":{"self":[{"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/posts\/20167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/comments?post=20167"}],"version-history":[{"count":0,"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/posts\/20167\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/media?parent=20167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/categories?post=20167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/tags?post=20167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}