{"id":20086,"date":"2021-08-28T20:39:34","date_gmt":"2021-08-28T20:39:34","guid":{"rendered":"https:\/\/blog.salarusinyol.net\/2021\/08\/28\/4-anotacions-de-fidel-bofill\/"},"modified":"2021-08-28T20:39:34","modified_gmt":"2021-08-28T20:39:34","slug":"4-anotacions-de-fidel-bofill","status":"publish","type":"post","link":"https:\/\/blog.salarusinyol.net\/en\/2021\/08\/28\/4-anotacions-de-fidel-bofill\/","title":{"rendered":"4 anotacions de\u2026 Fidel Bofill"},"content":{"rendered":"<p><strong>Respuestas r\u00e1pidas del artista, sin &#8220;buscar 3 patas al gato&#8221;<a rel=\"attachment wp-att-2501\" href=\"http:\/\/blogcat.salarusinyol.net\/?attachment_id=2501\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-2501\" title=\"fb-08\" src=\"http:\/\/bloc.salarusinyol.net\/wp-content\/uploads\/2010\/05\/fb-08-150x150.jpg\" alt=\"fb-08\" width=\"120\" height=\"120\" \/><\/a><\/strong><\/p>\n<ul>\n<li> <strong>T\u00fa? <\/strong>(nombre completo; poblaci\u00f3n y a\u00f1o nacimiento; y lo que quieras): <strong>Fidel Bofill Bosch<\/strong>. Vic, 1934. Casado; somos una familia de artesanos y artistas. Soy un pintor pintoresco.<\/li>\n<li> <strong>Una virtud tuya a destacar?<\/strong>: La de no tener ninguna virtud.<!--more--><\/li>\n<li> <strong>Un punto flaco tuyo a reconocer?<\/strong>: El sentimentalismo.<\/li>\n<li> <strong>Tu plato preferido? <\/strong>(para quien desee invitarte): Escamarlanes a la brasa.<\/li>\n<li> <strong>Un recuerdo de tu vida?<\/strong>: Cuando durante la guerra, con 5 a\u00f1os, me ametrallaron y no me tocaron. Fue en Gurb.<\/li>\n<li> <strong>Un lugar de este mundo?<\/strong>: Grecia.<\/li>\n<li> <strong>Un libro?<\/strong>: <em>&#8220;El quadern gris&#8221;<\/em>, de Josep Pla.<\/li>\n<li> <strong>Un escritor?<\/strong>: Bertrand Russell.<\/li>\n<li> <strong>Del &#8220;s\u00e9ptimo arte&#8221;: una pel\u00edcula?<\/strong>: <em>&#8220;Sopa de ganso&#8221;<\/em>, de los Hermanos Marx.<a rel=\"attachment wp-att-2502\" href=\"http:\/\/blogcat.salarusinyol.net\/?attachment_id=2502\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail  wp-image-2502\" title=\"fb-50\" src=\"http:\/\/bloc.salarusinyol.net\/wp-content\/uploads\/2010\/05\/fb-50-150x150.jpg\" alt=\"fb-50\" width=\"150\" height=\"150\" \/><\/a><\/li>\n<li> <strong>Una afici\u00f3n?<\/strong>: El oficio del burgu\u00e9s: comer, sentarse y no hacer nada.<\/li>\n<li> <strong>Un sue\u00f1o?<\/strong>: Vivir.<\/li>\n<li> <strong>Qu\u00e9 es el arte?<\/strong>: Disciplina que deber\u00eda entender todo el mundo. Cuando no lo entienden ya no es arte.<\/li>\n<li> <strong>Para Plat\u00f3n<\/strong>, <em>la <strong>belleza<\/strong> es la llamada de <strong>otro mundo<\/strong> para rescatarnos de la caverna donde vivimos<\/em>: (qu\u00e9 te parece?): Me suena a una expresi\u00f3n ultraderechista: quieren cambiar el mundo y no lo conseguir\u00e1n.<\/li>\n<li> <strong>Te has encontrado con la <span style=\"text-decoration: underline;\">B<\/span>elleza (as\u00ed, en <span style=\"text-decoration: underline;\">M<\/span>ay\u00fascula)?<\/strong>: S\u00ed, una puesta de sol.<\/li>\n<li> <strong>Tu maestro?<\/strong>: Joaquim Asensio.<\/li>\n<li> <strong>Te identificas con alguna escuela de pintura?<\/strong>: Paisajismo catal\u00e1n.<\/li>\n<li> <strong>Un pintor que admiras?<\/strong>: Joaquim Mir.<\/li>\n<li> <strong>Tu primer recuerdo del mundo del arte?<\/strong>: El primer cuadro, cuando ten\u00eda 12 a\u00f1os. Y lo conservo.<\/li>\n<li> <strong>Tu primera alegr\u00eda en el arte?<\/strong>: Cuando Lluis Marsillach (padre de Adolfo) hizo un art\u00edculo en el <em>Full del dilluns<\/em>: <em>&#8220;La vida se cuenta por semanas&#8221;<\/em>. Yo era muy joven.<\/li>\n<li> <strong>Tu primera exposici\u00f3n?<\/strong>: Como profesional, Berga en 1967. Antes ya hab\u00eda hecho cosas.<a rel=\"attachment wp-att-2503\" href=\"http:\/\/blogcat.salarusinyol.net\/?attachment_id=2503\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-2503\" title=\"dsc08040\" src=\"http:\/\/bloc.salarusinyol.net\/wp-content\/uploads\/2010\/05\/dsc08040-150x150.jpg\" alt=\"dsc08040\" width=\"150\" height=\"150\" \/><\/a><\/li>\n<li> <strong>Tu estilo?<\/strong>: <em>Campi qui pugui. Llibertat total <\/em>(que cada uno haga lo que pueda. Libertad total). Que cada uno ponga su etiqueta.<\/li>\n<li> <strong>Tu color?<\/strong>: Blanco<\/li>\n<li> <strong>Tu tema?<\/strong>: Todos.<\/li>\n<li> <strong>Nos dices algo m\u00e1s?<\/strong> (lo que quieras de lo que quieras): No.<\/li>\n<li><strong>Alguna otra pregunta? <\/strong>(que deseas que te hagamos): No.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Respuestas r\u00e1pidas del artista, sin &#8220;buscar 3 patas al gato&#8221; T\u00fa? (nombre completo; poblaci\u00f3n y a\u00f1o nacimiento; y lo que quieras): Fidel Bofill Bosch. Vic, 1934. Casado; somos una familia de artesanos y artistas. Soy un pintor pintoresco. Una virtud tuya a destacar?: La de no tener ninguna virtud.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-20086","post","type-post","status-publish","format-standard","hentry","category-4-apuntes-de"],"_links":{"self":[{"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/posts\/20086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/comments?post=20086"}],"version-history":[{"count":0,"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/posts\/20086\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/media?parent=20086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/categories?post=20086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/tags?post=20086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}