{"id":20085,"date":"2021-08-28T20:39:32","date_gmt":"2021-08-28T20:39:32","guid":{"rendered":"https:\/\/blog.salarusinyol.net\/2021\/08\/28\/homenatge-a-miquel-cabanas-i-alibau-11-29-v-2010\/"},"modified":"2021-08-28T20:39:32","modified_gmt":"2021-08-28T20:39:32","slug":"homenatge-a-miquel-cabanas-i-alibau-11-29-v-2010","status":"publish","type":"post","link":"https:\/\/blog.salarusinyol.net\/en\/2021\/08\/28\/homenatge-a-miquel-cabanas-i-alibau-11-29-v-2010\/","title":{"rendered":"Homenatge a Miquel Cabanas i Alibau (11-29.V.2010)"},"content":{"rendered":"<p><a rel=\"attachment wp-att-2482\" href=\"http:\/\/bloc.salarusinyol.net\/pinturafigurativa\/2010\/05\/homenatge-a-miquel-cabanas-i-alibau\/miquel-cabanas-cotxeres\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-2482\" title=\"miquel-cabanas-cotxeres\" src=\"http:\/\/bloc.salarusinyol.net\/wp-content\/uploads\/2010\/05\/miquel-cabanas-cotxeres-150x150.gif\" alt=\"miquel-cabanas-cotxeres\" width=\"118\" height=\"118\" \/><\/a>Ens omple de joia anunciar-vos que Espais d&#8217;Art Cotxeres-Casinet ret homenatge al meu estimat pare <strong><a href=\"http:\/\/www.salarusinyol.net\/cat\/curriculum\/miquel-cabanas_cat.html\">Miquel Cabanas<\/a><\/strong> (Sants, Barcelona 1916 &#8211; Sant Cugat del Vall\u00e8s 1995).<\/p>\n<p>Coneixedors de la traject\u00f2ria i qualitat de la seva obra, des de la direcci\u00f3 del centre han mostrat un gran inter\u00e8s en organitzar aquesta exposici\u00f3 que, sota el t\u00edtol d&#8217;<strong><em>&#8220;Antologia \u00edntima&#8221;<\/em><\/strong>, conjumina il\u00b7lustracions i passatges po\u00e8tics realitzats durant els \u00faltims deu anys de la seva vida.<\/p>\n<p>L&#8217;exposici\u00f3 s&#8217;inaugurar\u00e0 a les &#8220;Cotxeres de Sants&#8221; (c\/ Sants, 79 &#8211; 08014 Barcelona), el proper <strong>DIMARTS 11 a les 19:30 h<\/strong>.<!--more--><\/p>\n<p>La presentaci\u00f3 anir\u00e0 a c\u00e0rrec del periodista i escriptor Albert Torras i del muse\u00f2leg, historiador i cr\u00edtic d&#8217;art Ramon Casal\u00e9. Com a cloenda de l&#8217;acte, N\u00faria Feliu donar\u00e0 lectura als poemes.<\/p>\n<p><strong>Ignasi Cabanas Castells<\/strong> (Director de la Sala Rusi\u00f1ol)<\/p>\n<p style=\"text-align: center;\"><strong>* * *<\/strong><\/p>\n<p>Nos llena de alegr\u00eda anunciaros que Espais d&#8217;Art Cotxeres-Casinet rinde homenaje a mi querido padre <strong><a href=\"http:\/\/www.salarusinyol.net\/curriculum\/miquel-cabanas_cas.html\">Miquel Cabanas<\/a><\/strong> (Sants, Barcelona, 1916 &#8211; Sant Cugat del Vall\u00e8s, 1995).<\/p>\n<p>Conocedores de la trayectoria y calidad de su obra, desde la direcci\u00f3n del centro han mostrado un gran inter\u00e9s por organizar esta exposici\u00f3n que, bajo el t\u00edtulo de <strong><em>&#8220;Antolog\u00eda \u00edntima&#8221;<\/em><\/strong>, une ilustraciones y pasajes po\u00e9ticos realizados durante los \u00faltimos diez a\u00f1os de su vida.<\/p>\n<p>La exposici\u00f3n se inaugurar\u00e1 en las &#8220;Cotxeres de Sants&#8221; (c\/ Sants, 79 &#8211; 08014 Barcelona), el pr\u00f3ximo <strong>MARTES 11 a las 19:30 h<\/strong>.<\/p>\n<p>La presentaci\u00f3n ir\u00e1 a cargo del periodista y escritor Albert Torras y del muse\u00f3logo, historiador y cr\u00edtico de arte Ram\u00f3n Casal\u00e9. Para cerrar el acto, N\u00faria Feliu ser\u00e0 la encargada de dar lectura a las poes\u00edas.<\/p>\n<p><strong>Ignasi Cabanas Castells<\/strong> (Director de la Sala Rusi\u00f1ol)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ens omple de joia anunciar-vos que Espais d&#8217;Art Cotxeres-Casinet ret homenatge al meu estimat pare Miquel Cabanas (Sants, Barcelona 1916 &#8211; Sant Cugat del Vall\u00e8s 1995). Coneixedors de la traject\u00f2ria i qualitat de la seva obra, des de la direcci\u00f3 del centre han mostrat un gran inter\u00e8s en organitzar aquesta exposici\u00f3 que, sota el t\u00edtol [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-20085","post","type-post","status-publish","format-standard","hentry","category-art-i-sala-rusinyol"],"_links":{"self":[{"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/posts\/20085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/comments?post=20085"}],"version-history":[{"count":0,"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/posts\/20085\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/media?parent=20085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/categories?post=20085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/tags?post=20085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}