{"id":20024,"date":"2021-08-28T20:39:25","date_gmt":"2021-08-28T20:39:25","guid":{"rendered":"https:\/\/blog.salarusinyol.net\/2021\/08\/28\/4-anotacions-den-abel-florido\/"},"modified":"2021-08-28T20:39:25","modified_gmt":"2021-08-28T20:39:25","slug":"4-anotacions-den-abel-florido","status":"publish","type":"post","link":"https:\/\/blog.salarusinyol.net\/en\/2021\/08\/28\/4-anotacions-den-abel-florido\/","title":{"rendered":"&#8220;4 Anotacions d&#8217;en&#8230; Abel Florido&#8221;"},"content":{"rendered":"<p><strong><a href=\"http:\/\/blogcat.salarusinyol.net\/2016\/07\/09\/4-anotacions-den-abel-florido\/3-55\/\" rel=\"attachment wp-att-6301\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-6301\" src=\"http:\/\/blogcat.salarusinyol.net\/wp-content\/uploads\/2016\/07\/3-150x150.jpg\" alt=\"3\" width=\"150\" height=\"150\" \/><\/a>Respostes r\u00e0pides de l&#8217;artista, sense &#8220;cercar 3 potes al gat&#8221;<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>\u2022 <strong>Tu? <\/strong>(nom, naixen\u00e7a i el que vulguis): Abel Florido, nat a Barcelona el 1963.<\/p>\n<p><!--more--><\/p>\n<p>\u2022 <strong>Una virtut teva a destacar?<\/strong>:\u00a0La creativitat.<\/p>\n<p>\u2022 <strong>Un punt feble teu a recon\u00e8ixer?<\/strong>: Meticul\u00f3s en exc\u00e9s<\/p>\n<p>\u2022 <strong>El teu plat preferit? <\/strong>(per a qui desitgi convidar-te):\u00a0Fideu\u00e0.<\/p>\n<p>\u2022 <strong>Un record de la teva vida?<\/strong>:\u00a0Quan era molt petit, molt petit, el parc de M\u00aa Luisa, de Sevilla.<\/p>\n<p><strong>\u2022 Un r\u00e8cord en la teva vida? <\/strong>(pregunta afegida per suggeriment del pintor Rom\u00e1n Franc\u00e9s): Guanyar el primer premi de pintura a nivell nacional.<\/p>\n<p><a href=\"http:\/\/blogcat.salarusinyol.net\/2016\/07\/09\/4-anotacions-den-abel-florido\/2-49\/\" rel=\"attachment wp-att-6302\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-6302\" src=\"http:\/\/blogcat.salarusinyol.net\/wp-content\/uploads\/2016\/07\/2-150x150.jpg\" alt=\"2\" width=\"150\" height=\"150\" \/><\/a>\u2022 <strong>Un lloc d&#8217;aquest m\u00f3n?<\/strong>:\u00a0Gr\u00e8cia.<\/p>\n<p>\u2022 <strong>Un llibre?<\/strong>: <em>\u201cLa vuelta al mundo en 80 d\u00edas\u201d<\/em>.<\/p>\n<p>\u2022 <strong>Un escriptor?<\/strong>: Miguel de Cervantes.<\/p>\n<p>\u2022 <strong>Del &#8220;set\u00e8 art&#8221;: una pel\u00b7l\u00edcula?<\/strong>:\u00a0<em>\u201cLos muchachos del coro\u201d<\/em>. Tamb\u00e9: <em>\u201cLa vida es bella\u201d<\/em>.<\/p>\n<p>\u2022 <strong>Una afici\u00f3?<\/strong>:\u00a0Senderisme.<\/p>\n<p>\u2022 <strong>Un somni?<\/strong>:\u00a0Poder anar a l\u2019\u00cdndia.<\/p>\n<p>\u2022 <strong>Qu\u00e8 \u00e9s l&#8217;art?<\/strong>:\u00a0Interpretaci\u00f3 de la vida! En el meu cas es tracta d\u2019una mena d\u2019interpretaci\u00f3 del quotidi\u00e0, del que passa dins la ciutat.<\/p>\n<p>\u2022 <strong>Per a Plat\u00f3, <\/strong><em>la <strong>bellesa<\/strong> \u00e9s la crida d&#8217;<strong>un altre m\u00f3n<\/strong> per a rescatar-nos de la caverna on vivim<\/em> (qu\u00e8 et sembla?):\u00a0Molt profund! \u00c9s com sortir una mica d\u2019on som, com si fos una escapada.<\/p>\n<p>\u2022 <strong>T&#8217;has trobat amb la <span style=\"text-decoration: underline;\">B<\/span>ellesa (aix\u00ed, amb <span style=\"text-decoration: underline;\">M<\/span>aj\u00fascula)?<\/strong>:\u00a0S\u00ed, alguna vegada. Per exemple, quan surto a la muntanya, a la matinada o a la posta del sol. No \u00e9s un tema que entri dins del meu estil, per\u00f2 ho tinc present.<\/p>\n<p>\u2022 <strong>El teu mestre?<\/strong>: Va ser un pintor de Barcelona: vaig estar al seu taller treballant amb ell.<\/p>\n<p><a href=\"http:\/\/blogcat.salarusinyol.net\/2016\/07\/09\/4-anotacions-den-abel-florido\/4-51\/\" rel=\"attachment wp-att-6303\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-6303\" src=\"http:\/\/blogcat.salarusinyol.net\/wp-content\/uploads\/2016\/07\/4-150x150.jpg\" alt=\"4\" width=\"150\" height=\"150\" \/><\/a>\u2022 <strong>T&#8217;identifiques amb alguna escola de pintura?<\/strong>:\u00a0El meu tipus de pintura \u00e9s una mena <em>\u201cneo pot-art\u201d<\/em>. \u00c9s una re-invenci\u00f3.<\/p>\n<p>\u2022 <strong>Un pintor a qui admires?<\/strong>:\u00a0Picasso.<\/p>\n<p>\u2022 <strong>El teu primer record del m\u00f3n de l&#8217;art?<\/strong>:\u00a0Goya. El quadre de <em>\u201cEl fusilamiento del 2 de mayo\u201d<\/em> em va causar una gran impressi\u00f3 quan jo era menut. \u00c9s molt real de l\u2019\u00e8poca!<\/p>\n<p>\u2022 <strong>La teva primera alegria en l&#8217;art?<\/strong>:\u00a0Quan vaig veure que la gent li agradava aquest estil de pintura que vaig comen\u00e7ar.<\/p>\n<p>\u2022 <strong>La teva primera exposici\u00f3?<\/strong>:\u00a0A la Galeria <em>Jordi Barnadas<\/em>.<\/p>\n<p>\u2022 <strong>El teu estil?<\/strong>:\u00a0Figuratiu, paisatge urb\u00e0.<\/p>\n<p>\u2022 <strong>El teu color?<\/strong>:\u00a0M\u2019agrada molt el blanc i negre; el vermell perqu\u00e8 \u00e9s el que li d\u00f3na for\u00e7a al quadre.<\/p>\n<p>\u2022 <strong>El teu tema?<\/strong>:\u00a0El paisatge urb\u00e0 i la figura humana, tot integrat: figura humana dintre de la ciutat!<\/p>\n<p>\u2022 <strong>Ens dius quelcom m\u00e9s?<\/strong> (el que vulguis del que vulguis):\u00a0Com he dit abans, el meu estil consisteix a una mena de re-invenci\u00f3. En realitat, jo volia fer una cosa molt diferent, per\u00f2 em va passar el seg\u00fcent: un dia que era a l\u2019estiu, vaig fer una migdiada i, quan vaig despertar, vaig decidir fer persones en blanc i negre. Nom\u00e9s calia afegir-hi un color: el groc, vermell. Vaig anar a l\u2019estudi i ho vaig fer&#8230;<\/p>\n<p>\u2022 <strong>Alguna altra pregunta? <\/strong>(que desitgis que et fem):\u00a0No cal, ja est\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Respostes r\u00e0pides de l&#8217;artista, sense &#8220;cercar 3 potes al gat&#8221; &nbsp; \u2022 Tu? (nom, naixen\u00e7a i el que vulguis): Abel Florido, nat a Barcelona el 1963.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-20024","post","type-post","status-publish","format-standard","hentry","category-4-apuntes-de"],"_links":{"self":[{"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/posts\/20024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/comments?post=20024"}],"version-history":[{"count":0,"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/posts\/20024\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/media?parent=20024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/categories?post=20024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/tags?post=20024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}