{"id":19995,"date":"2021-08-28T20:39:24","date_gmt":"2021-08-28T20:39:24","guid":{"rendered":"https:\/\/blog.salarusinyol.net\/2021\/08\/28\/vernissatge-ulpiano-carrasco-6-marc-2015\/"},"modified":"2021-08-28T20:39:24","modified_gmt":"2021-08-28T20:39:24","slug":"vernissatge-ulpiano-carrasco-6-marc-2015","status":"publish","type":"post","link":"https:\/\/blog.salarusinyol.net\/en\/2021\/08\/28\/vernissatge-ulpiano-carrasco-6-marc-2015\/","title":{"rendered":"Vernissatge Ulpiano Carrasco (6 mar\u00e7 2015)"},"content":{"rendered":"<p><a rel=\"attachment wp-att-4421\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/04\/18\/vernissatge-den-tenorio-13-abril-2012\/01-tenorio-4\/\"><\/a><a rel=\"attachment wp-att-4432\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/05\/14\/vernissatge-den-lluis-roura-4-maig-2012\/01-roura\/\"><\/a><a rel=\"attachment wp-att-4506\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/06\/15\/vernissatge-daguilar-more\/01-aguilar-more\/\"><\/a><a rel=\"attachment wp-att-4511\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/06\/15\/vernissatge-daguilar-more\/01-aguilar-more-2\/\"><\/a><a rel=\"attachment wp-att-4552\" href=\"http:\/\/blogcat.salarusinyol.net\/2012\/09\/18\/vernissatge-de-miquel-peidro-7-setembre-2012\/01-peidro\/\"><\/a><\/p>\n<div style=\"height: 190px;\">\n<p><strong> <\/strong><strong> <\/strong><em> <\/em><strong><strong> <\/strong><\/strong><strong> <\/strong><\/p>\n<p><strong><a rel=\"attachment wp-att-5789\" href=\"http:\/\/blogcat.salarusinyol.net\/2015\/02\/10\/vernissatge-alicia-grau-6-febrer-2015-2\/1-32\/\"><\/a><\/strong><a rel=\"attachment wp-att-5826\" href=\"http:\/\/blogcat.salarusinyol.net\/2015\/03\/12\/vernissatge-ulpiano-carrasco-6-marc-2015\/3-37\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-5826\" title=\"3\" src=\"http:\/\/blogcat.salarusinyol.net\/wp-content\/uploads\/2015\/03\/3-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>Aquesta \u00e9s la segona vegada que presentem a la Sala Rusi\u00f1ol una exposici\u00f3 d\u2019Ulpiano Carrasco. Tampoc en aquesta ocasi\u00f3 ens deixa indiferents. La seva paleta i la visi\u00f3 dels paisatges de Cuenca s\u00f3n realment especials. Per\u00f2 a difer\u00e8ncia de l\u2019any 2011, avui ens acompanya la seva filla Elvira ja que l\u2019Ulpiano tenia un comprom\u00eds a Par\u00eds i no ha pogut arribar a temps.<\/p>\n<p><!--more--><\/p>\n<\/div>\n<div style=\"height: 200px;\">\n<p><a rel=\"attachment wp-att-5790\" href=\"http:\/\/blogcat.salarusinyol.net\/2015\/02\/10\/vernissatge-alicia-grau-6-febrer-2015-2\/2-32\/\"><\/a><a rel=\"attachment wp-att-5827\" href=\"http:\/\/blogcat.salarusinyol.net\/2015\/03\/12\/vernissatge-ulpiano-carrasco-6-marc-2015\/1-33\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-5827\" title=\"1\" src=\"http:\/\/blogcat.salarusinyol.net\/wp-content\/uploads\/2015\/03\/1-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>Josep M. Cadena: \u201cAmb les pintures de l\u2019Ulpiano Carrasco podem dir que ja ha arribat la primavera.\u00a0 Tenim una exposici\u00f3 que ens anima en aquests moments dif\u00edcils, perqu\u00e8 l\u2019artista creu en la capacitat de creure de les persones, en l\u2019alegria interior dels individus.\u201d<\/p>\n<\/div>\n<div style=\"height: 190px; text-align: right;\">\n<p><strong> <\/strong><strong><a rel=\"attachment wp-att-5791\" href=\"http:\/\/blogcat.salarusinyol.net\/2015\/02\/10\/vernissatge-alicia-grau-6-febrer-2015-2\/3-36\/\"><\/a><\/strong><a rel=\"attachment wp-att-5828\" href=\"http:\/\/blogcat.salarusinyol.net\/2015\/03\/12\/vernissatge-ulpiano-carrasco-6-marc-2015\/2-33\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-5828\" title=\"2\" src=\"http:\/\/blogcat.salarusinyol.net\/wp-content\/uploads\/2015\/03\/2-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>Continua Cadena: L\u2019Ulpiano no nom\u00e9s ens mostra paisatges de Cuenca. Ell ha viatjat molt i aix\u00f2 queda reflectit als temes urbans que podem veure en aquesta exposici\u00f3 on \u00e9s remarcable l\u00b4\u00fas dels colors fluor. Clara mostra de la seva internacionalitat \u00e9s que fa ja un temps em van demanar un article per una exposici\u00f3 que havia de fer a Saigon. \u201cL\u2019Ulpiano m\u2019ha fet tamb\u00e9 internacional sense saber-ho!\u201d.<\/p>\n<p><strong> <\/strong><strong> <\/strong><strong> <\/strong><\/p>\n<\/div>\n<div style=\"height: 190px; text-align: left;\">\n<p><strong><strong> <\/strong><\/strong><strong> <\/strong><strong> <\/strong><strong><a rel=\"attachment wp-att-5792\" href=\"http:\/\/blogcat.salarusinyol.net\/2015\/02\/10\/vernissatge-alicia-grau-6-febrer-2015-2\/4-35\/\"><\/a><\/strong><a rel=\"attachment wp-att-5829\" href=\"http:\/\/blogcat.salarusinyol.net\/2015\/03\/12\/vernissatge-ulpiano-carrasco-6-marc-2015\/4-36\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-5829\" title=\"4\" src=\"http:\/\/blogcat.salarusinyol.net\/wp-content\/uploads\/2015\/03\/4-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a> En aquest moment l&#8217;Ignasi Cabanas passa la paraula a L\u2019Elvira Carrasco, filla de l\u2019artista: El meu pare \u00e9s un geni. A banda del meu pare tamb\u00e9 \u00e9s el meu mestre. M\u2019ha ensenyat molt\u00edssimes coses ja des de ben petita. Sempre m\u2019animava a pintar \u201cElvira, tu pinta el que vulguis\u201d em deia. Fins i tot em feia retrats. La seva obra ha anat evolucionant al llarg de tots aquests anys, des dels colors foscos dels anys 80 fins la for\u00e7a del color a \u201cTempus Fluor\u201d.<\/p>\n<\/div>\n<div style=\"height: 210px; text-align: right;\">\n<p><strong> <\/strong><strong><a rel=\"attachment wp-att-5793\" href=\"http:\/\/blogcat.salarusinyol.net\/2015\/02\/10\/vernissatge-alicia-grau-6-febrer-2015-2\/5-33\/\"><\/a><\/strong><a rel=\"attachment wp-att-5830\" href=\"http:\/\/blogcat.salarusinyol.net\/2015\/03\/12\/vernissatge-ulpiano-carrasco-6-marc-2015\/5-34\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-5830\" title=\"5\" src=\"http:\/\/blogcat.salarusinyol.net\/wp-content\/uploads\/2015\/03\/5-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>Arriba el torn de les preguntes:\u00a0 \u201c-S\u2019inspira en algun pintor? Inicialment en Zurbar\u00e1n per\u00f2 ja fa anys que no s\u2019inspira en ning\u00fa. Ell segueix el seu propi cam\u00ed\u201d \u201c-Per\u00f2 tindr\u00e0 un pintor favorit? S\u00ed. Van Gogh. De fet li diuen el \u201cVan Gogh de la Jara\u201d. \u201c-Que tal pinta si ha de fer un retrat? Sabria fer-te un retrat realista perqu\u00e8 t\u00e9 un gran domini del dibuix per\u00f2 ell el faria m\u00e9s al seu estil, m\u00e9s expressionista\u201d.<\/p>\n<p style=\"font-weight: bold;\">\n<\/div>\n<p style=\"text-align: center;\"><strong>M\u00c9S FOTOS  DEL VERNISSATGE<\/strong><\/p>\n<div style=\"height: 160px; display: block;\"><a rel=\"attachment wp-att-5796\" href=\"http:\/\/blogcat.salarusinyol.net\/2015\/02\/10\/vernissatge-alicia-grau-6-febrer-2015-2\/6-28\/\"><\/a><a rel=\"attachment wp-att-5831\" href=\"http:\/\/blogcat.salarusinyol.net\/2015\/03\/12\/vernissatge-ulpiano-carrasco-6-marc-2015\/6-29\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-5831\" title=\"6\" src=\"http:\/\/blogcat.salarusinyol.net\/wp-content\/uploads\/2015\/03\/6-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/div>\n<div style=\"height: 160px; display: block;\"><a rel=\"attachment wp-att-5797\" href=\"http:\/\/blogcat.salarusinyol.net\/2015\/02\/10\/vernissatge-alicia-grau-6-febrer-2015-2\/7-28\/\"><\/a><a rel=\"attachment wp-att-5832\" href=\"http:\/\/blogcat.salarusinyol.net\/2015\/03\/12\/vernissatge-ulpiano-carrasco-6-marc-2015\/7-29\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-5832\" title=\"7\" src=\"http:\/\/blogcat.salarusinyol.net\/wp-content\/uploads\/2015\/03\/7-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/div>\n<div style=\"height: 160px; display: block;\"><a rel=\"attachment wp-att-5798\" href=\"http:\/\/blogcat.salarusinyol.net\/2015\/02\/10\/vernissatge-alicia-grau-6-febrer-2015-2\/8-28\/\"><\/a><a rel=\"attachment wp-att-5833\" href=\"http:\/\/blogcat.salarusinyol.net\/2015\/03\/12\/vernissatge-ulpiano-carrasco-6-marc-2015\/8-29\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-5833\" title=\"8\" src=\"http:\/\/blogcat.salarusinyol.net\/wp-content\/uploads\/2015\/03\/8-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/div>\n<div style=\"height: 160px; display: block;\"><a rel=\"attachment wp-att-5805\" href=\"http:\/\/blogcat.salarusinyol.net\/2015\/02\/10\/vernissatge-alicia-grau-6-febrer-2015-2\/9-31\/\"><\/a><a rel=\"attachment wp-att-5834\" href=\"http:\/\/blogcat.salarusinyol.net\/2015\/03\/12\/vernissatge-ulpiano-carrasco-6-marc-2015\/9-32\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-5834\" title=\"9\" src=\"http:\/\/blogcat.salarusinyol.net\/wp-content\/uploads\/2015\/03\/9-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/div>\n<div style=\"height: 160px; display: block;\"><a rel=\"attachment wp-att-5806\" href=\"http:\/\/blogcat.salarusinyol.net\/2015\/02\/10\/vernissatge-alicia-grau-6-febrer-2015-2\/10-28\/\"><\/a><a rel=\"attachment wp-att-5835\" href=\"http:\/\/blogcat.salarusinyol.net\/2015\/03\/12\/vernissatge-ulpiano-carrasco-6-marc-2015\/10-29\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-5835\" title=\"10\" src=\"http:\/\/blogcat.salarusinyol.net\/wp-content\/uploads\/2015\/03\/10-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/div>\n<div style=\"height: 160px; display: block;\"><a rel=\"attachment wp-att-5807\" href=\"http:\/\/blogcat.salarusinyol.net\/2015\/02\/10\/vernissatge-alicia-grau-6-febrer-2015-2\/11-30\/\"><\/a><a rel=\"attachment wp-att-5836\" href=\"http:\/\/blogcat.salarusinyol.net\/2015\/03\/12\/vernissatge-ulpiano-carrasco-6-marc-2015\/11-31\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-5836\" title=\"11\" src=\"http:\/\/blogcat.salarusinyol.net\/wp-content\/uploads\/2015\/03\/11-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/div>\n<div style=\"height: 160px; display: block;\"><a rel=\"attachment wp-att-5808\" href=\"http:\/\/blogcat.salarusinyol.net\/2015\/02\/10\/vernissatge-alicia-grau-6-febrer-2015-2\/12-29\/\"><\/a><a rel=\"attachment wp-att-5837\" href=\"http:\/\/blogcat.salarusinyol.net\/2015\/03\/12\/vernissatge-ulpiano-carrasco-6-marc-2015\/12-30\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-5837\" title=\"12\" src=\"http:\/\/blogcat.salarusinyol.net\/wp-content\/uploads\/2015\/03\/12-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/div>\n<div style=\"height: 160px; display: block;\"><a rel=\"attachment wp-att-5809\" href=\"http:\/\/blogcat.salarusinyol.net\/2015\/02\/10\/vernissatge-alicia-grau-6-febrer-2015-2\/13-28\/\"><\/a><\/div>\n<div style=\"height: 160px; display: block;\"><a rel=\"attachment wp-att-5810\" href=\"http:\/\/blogcat.salarusinyol.net\/2015\/02\/10\/vernissatge-alicia-grau-6-febrer-2015-2\/14-28\/\"><\/a><\/div>\n<div style=\"height: 160px; display: block;\"><a rel=\"attachment wp-att-5811\" href=\"http:\/\/blogcat.salarusinyol.net\/2015\/02\/10\/vernissatge-alicia-grau-6-febrer-2015-2\/15-30\/\"><\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Aquesta \u00e9s la segona vegada que presentem a la Sala Rusi\u00f1ol una exposici\u00f3 d\u2019Ulpiano Carrasco. Tampoc en aquesta ocasi\u00f3 ens deixa indiferents. La seva paleta i la visi\u00f3 dels paisatges de Cuenca s\u00f3n realment especials. Per\u00f2 a difer\u00e8ncia de l\u2019any 2011, avui ens acompanya la seva filla Elvira ja que l\u2019Ulpiano tenia un comprom\u00eds a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-19995","post","type-post","status-publish","format-standard","hentry","category-vernissatges-a-la-sala-rusinol"],"_links":{"self":[{"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/posts\/19995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/comments?post=19995"}],"version-history":[{"count":0,"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/posts\/19995\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/media?parent=19995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/categories?post=19995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.salarusinyol.net\/en\/wp-json\/wp\/v2\/tags?post=19995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}